{"id":48,"date":"2019-10-25T02:09:22","date_gmt":"2019-10-25T00:09:22","guid":{"rendered":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/?p=48"},"modified":"2019-10-25T02:31:11","modified_gmt":"2019-10-25T00:31:11","slug":"der-musikunterricht","status":"publish","type":"post","link":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/2019\/10\/25\/der-musikunterricht\/","title":{"rendered":"Der Musikunterricht"},"content":{"rendered":"\n<p>Wie l\u00e4uft eigentlich unser Musikunterricht hier? <br>Zum einen gibt es die Grundschulen, in denen wir immer morgens unterrichten. Hier singen wir einfach gemeinsam verschiedene Lieder zum Beispiel: &#8222;Head and shoulders knees and toes&#8220;. <br>Manchmal ist es schwierig die Kids unter Kontrolle zu halten, weil sie auch gerne einfach mal nur rum rennen. <br>Die ganz kleinen Kids trauen sich auch oft nicht zu singen, da m\u00fcssen wir uns manchmal ziemlich anstrengen, sie zum Singen zu bekommen. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-21-19-47-22.jpg\" alt=\"\" class=\"wp-image-58\" width=\"314\" height=\"188\" srcset=\"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-21-19-47-22.jpg 971w, https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-21-19-47-22-300x180.jpg 300w, https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-21-19-47-22-768x462.jpg 768w\" sizes=\"(max-width: 314px) 100vw, 314px\" \/><figcaption>Fl\u00f6tenunterricht<\/figcaption><\/figure><\/div>\n\n\n\n<p><br>In einer Schule geben wir Fl\u00f6tenunterricht. Da bringen wir den Kindern ein paar T\u00f6ne bei, das Ziel ist die Melodie von &#8222;One Love&#8220;.<br>In den Schulen sind die Kinder haupts\u00e4chlich zwischen 3 und 10 Jahre alt (wir unterrichten verschiedene Klassen). <br>Freitags sind wir in einer Schule mit behinderten Sch\u00fclern. <\/p>\n\n\n\n<p>Der Einzelunterricht im instrumentalen Bereich ist bis jetzt bei mir noch ziemlich unorganisiert. Ich habe bis jetzt noch nicht so viele Sch\u00fcler, aber mein Plan ist, mir einen gr\u00f6\u00dferen Sch\u00fclerkreis aufzubauen. <br>Oft kommen hier auch einfach Kids her und sehen den Unterricht als Belustigung. Aber ich habe auch ein paar \u00e4ltere Sch\u00fcler, mit denen es echt Spa\u00df macht zu arbeiten. Oft lernen wir auch gegenseitig voneinander. Ein Geben und Nehmen. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-24-18-38-40-1-768x1024.jpg\" alt=\"\" class=\"wp-image-71\" width=\"253\" height=\"337\" srcset=\"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-24-18-38-40-1-768x1024.jpg 768w, https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-24-18-38-40-1-225x300.jpg 225w, https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-content\/uploads\/sites\/41\/2019\/10\/2019-10-24-18-38-40-1.jpg 1200w\" sizes=\"(max-width: 253px) 100vw, 253px\" \/><figcaption>Spontane Jamsession auf der Dachterrasse<\/figcaption><\/figure><\/div>\n\n\n\n<p><br>Gejammt haben wir einen Abend auch schon. Das war ziemlich spontan und niemand war vorbereitet, aber es hat echt Spa\u00df gemacht. N\u00e4chstes Mal sind wir alle besser vorbereitet. \ud83d\ude42<br><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie l\u00e4uft eigentlich unser Musikunterricht hier? Zum einen gibt es die Grundschulen, in denen wir immer morgens unterrichten. Hier singen wir einfach gemeinsam verschiedene Lieder zum Beispiel: &#8222;Head and shoulders knees and toes&#8220;. Manchmal ist es schwierig die Kids unter &hellip; <a href=\"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/2019\/10\/25\/der-musikunterricht\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/posts\/48"}],"collection":[{"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":17,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/posts\/48\/revisions"}],"predecessor-version":[{"id":72,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/posts\/48\/revisions\/72"}],"wp:attachment":[{"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/categories?post=48"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.musikerohnegrenzen.de\/rebeccafichtl\/wp-json\/wp\/v2\/tags?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}